{"id":2833095,"date":"2026-07-06T14:30:27","date_gmt":"2026-07-06T14:30:27","guid":{"rendered":"https:\/\/carlossebastiao.com\/produto\/lava-louca-iberico-inox-50-200mm-enc-baixo-banka\/"},"modified":"2026-07-07T15:43:35","modified_gmt":"2026-07-07T15:43:35","slug":"lava-louca-iberico-inox-50-200mm-enc-baixo-banka","status":"publish","type":"product","link":"https:\/\/carlossebastiao.com\/en\/product\/lava-louca-iberico-inox-50-200mm-enc-baixo-banka\/","title":{"rendered":"Lava Lou\u00e7a Iberico Inox 50-200mm Enc.Baixo Banka"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":2833100,"template":"","meta":[],"product_cat":[50],"product_tag":[],"class_list":["post-2833095","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-lava-loucas-e-cozinha"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lava Lou\u00e7a Iberico Inox 50-200mm Enc.Baixo Banka Carlos Alberto Tavares Sebasti\u00e3o e Filhos, Lda -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/carlossebastiao.com\/en\/product\/lava-louca-iberico-inox-50-200mm-enc-baixo-banka\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lava Lou\u00e7a Iberico Inox 50-200mm Enc.Baixo Banka Carlos Alberto Tavares Sebasti\u00e3o e Filhos, Lda -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/carlossebastiao.com\/en\/product\/lava-louca-iberico-inox-50-200mm-enc-baixo-banka\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlos Alberto Tavares Sebasti\u00e3o e Filhos, Lda\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T15:43:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/carlossebastiao.com\/wp-content\/uploads\/imagens\/analisadas\/31638.PNG\" \/>\n\t<meta property=\"og:image:width\" content=\"967\" \/>\n\t<meta property=\"og:image:height\" content=\"873\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/carlossebastiao.com\/produto\/lava-louca-iberico-inox-50-200mm-enc-baixo-banka\/\",\"url\":\"https:\/\/carlossebastiao.com\/produto\/lava-louca-iberico-inox-50-200mm-enc-baixo-banka\/\",\"name\":\"Lava Lou\u00e7a Iberico Inox 50-200mm Enc.Baixo Banka Carlos Alberto Tavares Sebasti\u00e3o e Filhos, Lda -\",\"isPartOf\":{\"@id\":\"https:\/\/carlossebastiao.com\/#website\"},\"datePublished\":\"2026-07-06T14:30:27+00:00\",\"dateModified\":\"2026-07-07T15:43:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/carlossebastiao.com\/produto\/lava-louca-iberico-inox-50-200mm-enc-baixo-banka\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/carlossebastiao.com\/produto\/lava-louca-iberico-inox-50-200mm-enc-baixo-banka\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/carlossebastiao.com\/produto\/lava-louca-iberico-inox-50-200mm-enc-baixo-banka\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/carlossebastiao.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja Online\",\"item\":\"https:\/\/carlossebastiao.com\/loja-online\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lava Lou\u00e7a Iberico Inox 50-200mm Enc.Baixo Banka\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/carlossebastiao.com\/#website\",\"url\":\"https:\/\/carlossebastiao.com\/\",\"name\":\"Carlos Alberto Tavares Sebasti\u00e3o e Filhos, Lda\",\"description\":\"Materiais de constru\u00e7\u00e3o, Constru\u00e7\u00e3o Civil, Loja de ferragens, Carpintaria em S\u00e3o Miguel A\u00e7ores\",\"publisher\":{\"@id\":\"https:\/\/carlossebastiao.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/carlossebastiao.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/carlossebastiao.com\/#organization\",\"name\":\"Carlos Alberto Tavares Sebasti\u00e3o e Filhos, Lda\",\"url\":\"https:\/\/carlossebastiao.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/carlossebastiao.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/carlossebastiao.com\/wp-content\/uploads\/2023\/09\/logo-carlossebastiao.png\",\"contentUrl\":\"https:\/\/carlossebastiao.com\/wp-content\/uploads\/2023\/09\/logo-carlossebastiao.png\",\"width\":400,\"height\":166,\"caption\":\"Carlos Alberto Tavares Sebasti\u00e3o e Filhos, Lda\"},\"image\":{\"@id\":\"https:\/\/carlossebastiao.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lava Lou\u00e7a Iberico Inox 50-200mm Enc.Baixo Banka Carlos Alberto Tavares Sebasti\u00e3o e Filhos, Lda -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/carlossebastiao.com\/en\/product\/lava-louca-iberico-inox-50-200mm-enc-baixo-banka\/","og_locale":"en_US","og_type":"article","og_title":"Lava Lou\u00e7a Iberico Inox 50-200mm Enc.Baixo Banka Carlos Alberto Tavares Sebasti\u00e3o e Filhos, Lda -","og_url":"https:\/\/carlossebastiao.com\/en\/product\/lava-louca-iberico-inox-50-200mm-enc-baixo-banka\/","og_site_name":"Carlos Alberto Tavares Sebasti\u00e3o e Filhos, Lda","article_modified_time":"2026-07-07T15:43:35+00:00","og_image":[{"width":967,"height":873,"url":"https:\/\/carlossebastiao.com\/wp-content\/uploads\/imagens\/analisadas\/31638.PNG","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/carlossebastiao.com\/produto\/lava-louca-iberico-inox-50-200mm-enc-baixo-banka\/","url":"https:\/\/carlossebastiao.com\/produto\/lava-louca-iberico-inox-50-200mm-enc-baixo-banka\/","name":"Lava Lou\u00e7a Iberico Inox 50-200mm Enc.Baixo Banka Carlos Alberto Tavares Sebasti\u00e3o e Filhos, Lda -","isPartOf":{"@id":"https:\/\/carlossebastiao.com\/#website"},"datePublished":"2026-07-06T14:30:27+00:00","dateModified":"2026-07-07T15:43:35+00:00","breadcrumb":{"@id":"https:\/\/carlossebastiao.com\/produto\/lava-louca-iberico-inox-50-200mm-enc-baixo-banka\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/carlossebastiao.com\/produto\/lava-louca-iberico-inox-50-200mm-enc-baixo-banka\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/carlossebastiao.com\/produto\/lava-louca-iberico-inox-50-200mm-enc-baixo-banka\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/carlossebastiao.com\/"},{"@type":"ListItem","position":2,"name":"Loja Online","item":"https:\/\/carlossebastiao.com\/loja-online\/"},{"@type":"ListItem","position":3,"name":"Lava Lou\u00e7a Iberico Inox 50-200mm Enc.Baixo Banka"}]},{"@type":"WebSite","@id":"https:\/\/carlossebastiao.com\/#website","url":"https:\/\/carlossebastiao.com\/","name":"Carlos Alberto Tavares Sebasti\u00e3o e Filhos, Lda","description":"Materiais de constru\u00e7\u00e3o, Constru\u00e7\u00e3o Civil, Loja de ferragens, Carpintaria em S\u00e3o Miguel A\u00e7ores","publisher":{"@id":"https:\/\/carlossebastiao.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/carlossebastiao.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/carlossebastiao.com\/#organization","name":"Carlos Alberto Tavares Sebasti\u00e3o e Filhos, Lda","url":"https:\/\/carlossebastiao.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/carlossebastiao.com\/#\/schema\/logo\/image\/","url":"https:\/\/carlossebastiao.com\/wp-content\/uploads\/2023\/09\/logo-carlossebastiao.png","contentUrl":"https:\/\/carlossebastiao.com\/wp-content\/uploads\/2023\/09\/logo-carlossebastiao.png","width":400,"height":166,"caption":"Carlos Alberto Tavares Sebasti\u00e3o e Filhos, Lda"},"image":{"@id":"https:\/\/carlossebastiao.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/carlossebastiao.com\/en\/wp-json\/wp\/v2\/product\/2833095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carlossebastiao.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/carlossebastiao.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carlossebastiao.com\/en\/wp-json\/wp\/v2\/media\/2833100"}],"wp:attachment":[{"href":"https:\/\/carlossebastiao.com\/en\/wp-json\/wp\/v2\/media?parent=2833095"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/carlossebastiao.com\/en\/wp-json\/wp\/v2\/product_cat?post=2833095"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/carlossebastiao.com\/en\/wp-json\/wp\/v2\/product_tag?post=2833095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}